{"id":13363,"date":"2025-03-20T12:28:10","date_gmt":"2025-03-20T11:28:10","guid":{"rendered":"https:\/\/refinery89.com\/?p=13363"},"modified":"2025-07-16T15:14:05","modified_gmt":"2025-07-16T13:14:05","slug":"core-web-vitals-der-guide","status":"publish","type":"post","link":"https:\/\/refinery89.com\/de\/core-web-vitals-guide\/","title":{"rendered":"Core Web Vitals: Der ultimative Guide zur Verbesserung der Website-Performance"},"content":{"rendered":"<p>Die st\u00e4ndige Optimierung deiner Website ist genau das, was der Doktor verordnet hat, um eine gesunde Werbestrategie aufrechtzuerhalten. Und eine M\u00f6glichkeit, das zu tun, ist, deine <a href=\"https:\/\/web.dev\/articles\/vitals\">ore Web Vitals-Krise \u2013<\/a>im Blick zu behalten. Diese bekannten Kennzahlen zeigen dir, wie gut deine Website performt \u2013 und geben dir wertvolle Hinweise, wie du das Nutzererlebnis verbessern, dein Suchmaschinenranking steigern und vor allem deine Werbeeinnahmen erh\u00f6hen kannst!<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Was sind die Core Web Vitals?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-13364 size-full\" src=\"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers.png\" alt=\"Google's Core Web Vitals\" width=\"2903\" height=\"999\" srcset=\"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers.png 2903w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-300x103.png 300w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-1024x352.png 1024w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-768x264.png 768w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-1536x529.png 1536w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-2048x705.png 2048w, https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/CWV-Metrics-for-publishers-18x6.png 18w\" sizes=\"(max-width: 2903px) 100vw, 2903px\" \/><\/p>\n<p>Core Web Vitals sind nutzerzentrierte Metriken von <a href=\"https:\/\/developers.google.com\/search\/docs\/appearance\/core-web-vitals\">Google<\/a>, mit denen die User Experience auf einer Website gemessen wird \u2013 basierend auf Ladezeit, Reaktionsf\u00e4higkeit und visueller Stabilit\u00e4t. Es gibt drei zentrale Kennzahlen, die gro\u00dfartige Publisher wie du auf keinen Fall ignorieren sollten:<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Largest Contentful Paint (LCP)<\/strong><\/h3>\n<p>Der Largest Contentful Paint, auch bekannt als LCP, misst die Ladeleistung deiner Webseiten und zeigt, wie schnell der Hauptinhalt einer Seite sichtbar wird. Dabei wird gemessen, wie lange es dauert, bis das gr\u00f6\u00dfte Textfeld, Bild oder Video im sichtbaren Bereich des Nutzers gerendert wird. Um diesen Wert mit Bravour zu bestehen, solltest du einen LCP-Wert von 2,5 Sekunden oder weniger anstreben.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Interaction to Next Paint (INP)<\/strong><\/h3>\n<p>Der Interaction to Next Paint, kurz INP, beschreibt die Interaktivit\u00e4t deiner Webseite. Er misst, wie schnell deine Seite auf Nutzeraktionen reagiert. Zum Beispiel: Wenn du ein T-Shirt in den Warenkorb legst, aktualisiert sich das Warenkorb-Symbol und zeigt den neuen Artikel an.<\/p>\n<p>Der ideale INP-Wert f\u00fcr dich liegt bei 200 Millisekunden oder weniger. Ein niedriger INP bedeutet, dass deine Website schnell reagiert und dem Nutzer visuelles Feedback auf seine Aktionen gibt. Wenn du das schon erreicht hast \u2013 100 Punkte f\u00fcr dein Haus!<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Cumulative Layout Shift (CLS)<\/strong><\/h3>\n<p>Ist es dir schon mal passiert, dass du einen Artikel auf einer Website liest und pl\u00f6tzlich ein Bild oder eine Anzeige fertig l\u00e4dt, wodurch die ganze Seite dich vom Lesen ablenkt? Das macht einem wirklich Lust, gegen die Wand zu hauen. Der Cumulative Layout Shift, oder kurz CLS, ist die Core Web Vital, die die Stabilit\u00e4t deiner Website beschreibt. Sie misst die unerwarteten Verschiebungen im Layout deiner Seite. Diese Verschiebungen sind wirklich nervig f\u00fcr jeden Internetnutzer! Also versuche immer, deinen CLS unter 0,1 zu halten.<\/p>\n<p>Diese Verschiebungen passieren oft, weil hochgeladene Bilder oder Werbefl\u00e4chen keine festen Dimensionen haben und der Browser keinen \u201ePlatz\u201c reserviert. Dadurch verschiebt sich das Layout, wenn ein Bild schlie\u00dflich gerendert wird und seine Gr\u00f6\u00dfe offenbart. Du kannst das vermeiden, indem du sicherstellst, dass der entsprechende Platz f\u00fcr die Slots im Voraus reserviert wurde, sodass die Einheiten in diesen Raum eingef\u00fcgt werden, ohne dass der Inhalt nach oben oder unten verschoben werden muss.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Warum sind Core Web Vitals f\u00fcr Publisher wichtig?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Obwohl Core Web Vitals nicht der einzige Faktor sind, der das Ranking deiner Website in den Suchmaschinen bestimmt, beeinflussen sie die Anzeigenleistung deiner Seite. Kleine Details k\u00f6nnen immer noch den Unterschied machen! Hier sind einige wichtige Gr\u00fcnde, warum Core Web Vitals-\u00dcberpr\u00fcfungen nicht aus deiner Routine fehlen sollten:<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Du hast nur eine Chance f\u00fcr einen ersten Eindruck.<\/strong><\/h3>\n<p>Die Core Web Vitals bestimmen die erste Wahrnehmung der Nutzer bez\u00fcglich der Reaktionsf\u00e4higkeit deiner Seite. Basierend auf diesem ersten Eindruck entscheidet der Besucher, ob er weiterhin mit deinem Inhalt (einschlie\u00dflich deiner Anzeigen!) interagieren m\u00f6chte oder im schlimmsten Fall zur Seite nebenan wechselt.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Sorge f\u00fcr eine gute Benutzererfahrung.<\/strong><\/h3>\n<p>Frustrierte Nutzer verringern das Engagement auf deiner Seite, was du ben\u00f6tigst, um mehr Impressionen und Interaktionen mit deinen Anzeigen zu generieren. Eine signifikante Verz\u00f6gerung oder Layout-Verschiebungen lassen die Nutzer das Gef\u00fchl haben, dass die Interaktionen verz\u00f6gert sind und die Seite langsam l\u00e4dt, was zu einer hohen Absprungrate f\u00fchrt.\u00a0<a href=\"https:\/\/refinery89.com\/de\/4-ways-to-improve-your-websites-user-experience\/\" target=\"_blank\" rel=\"noopener\">Du kannst mehr \u00fcber die Auswirkungen der Nutzererfahrung auf deine Website und wie du sie verbessern kannst, in diesem Artikel von Itziar, unserer internen UX-Leiterin, erfahren!<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Verbessere deine SEO-Strategie<\/strong><\/h3>\n<p>Die Core Web Vitals beeinflussen die Positionierung deiner Website auf den Suchergebnisseiten (SERPs). Google neigt dazu, responsive Seiten zu belohnen, die nicht ewig zum Laden brauchen, schnelle R\u00fcckmeldungen auf Nutzerinteraktionen liefern und das Layout nicht verschieben, sobald der Inhalt gerendert ist, um eine bessere Nutzererfahrung zu gew\u00e4hrleisten. Je besser deine Seite funktioniert, desto besser wird sie auf den SERPs platziert.\u00a0<a href=\"https:\/\/refinery89.com\/de\/seo-for-publishers-how-to-start-optimizing\/\" target=\"_blank\" rel=\"noopener\">Folge diesem SEO-Guide f\u00fcr Publisher, den wir erstellt haben, um zu lernen, wie du deine Strategie optimieren kannst.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Optimiere deine Anzeigenmonetarisierung.<\/strong><\/h3>\n<p>Werbung ist ein Element einer Website, das, wenn es nicht richtig gepflegt wird, die Benutzererfahrung negativ beeinflussen kann. Und um deine Taschen mit Werbeeinnahmen zu f\u00fcllen, ben\u00f6tigst du funktionale Anzeigen als Teil deiner Monetarisierungsstrategie! Finde das richtige Gleichgewicht zwischen einer gro\u00dfartigen Benutzererfahrung f\u00fcr deine Besucher und der Optimierung der Anzeigenleistung.<\/p>\n<p>Eine M\u00f6glichkeit, die Anzeigenleistung zu optimieren, ist die Verwendung von Methoden zum Verkauf von Werbefl\u00e4chen, die die Ladegeschwindigkeit deiner Anzeigenpl\u00e4tze verbessern, wie zum Beispiel Header Bidding. Schau dir\u00a0<a href=\"https:\/\/web.dev\/articles\/loading-ads-page-speed\" target=\"_blank\" rel=\"noopener\">diese Empfehlungen von Chrome\u2019s Web.dev an, um Anzeigen effizient zu laden, ohne die Ladegeschwindigkeit zu beeintr\u00e4chtigen.<\/a><\/p>\n<p>Ein weiterer gro\u00dfartiger Tipp ist es, die Werbefl\u00e4chen bewusst auf der Webseite zu platzieren, damit sie ihre Position nicht \u00e4ndern oder deine Nutzer nicht \u00fcberfordern.\u00a0<a href=\"https:\/\/refinery89.com\/de\/4-strategien-zur-anzeigenplatzierung-zur-maximierung-der-einnahmen\/\" target=\"_blank\" rel=\"noopener\">Erfahre, wie du deine Werbeeinnahmen mit diesen Platzierungsstrategien von unserem AdOps-Experten Germ\u00e1n Tinaut maximieren kannst!<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Wie man die Core Web Vitals verfolgt?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Eine der gr\u00f6\u00dften Erfindungen seit dem Feuer sind Online-Tools, die uns im Alltag helfen. Okay, das mag ein wenig dramatisch sein, aber es ist wahr, dass es viele praktische Tools gibt, die das Verfolgen von Metriken zum Kinderspiel machen. Einige der besten Tools zur Verfolgung deiner Core Web Vitals sind:<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Google Search Console<\/strong><\/h3>\n<p>Die gute alte <a href=\"https:\/\/search.google.com\/search-console\/about\" target=\"_blank\" rel=\"noopener\">Google Search Console<\/a> hat einen speziellen Abschnitt nur f\u00fcr die Core Web Vitals, der einen \u00dcberblick \u00fcber die gesamte Website bietet. Sie zeigt dir auch die Seiten, die Verbesserungen ben\u00f6tigen, damit du sie so schnell wie m\u00f6glich angehen kannst.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Google Page Speed Insights<\/strong><\/h3>\n<p><a href=\"https:\/\/pagespeed.web.dev\/\" target=\"_blank\" rel=\"noopener\">Google Page Speed Insights<\/a> ist ein beliebtes Tool, das in deinem Toolkit nicht fehlen darf. Es bietet eine Leistungsanalyse f\u00fcr mobile Ger\u00e4te und Desktops. Es liefert eine Bewertung der Core Web Vitals deiner Website und, als ob das nicht genug w\u00e4re, gibt es auch Empfehlungen, wie du diese optimieren kannst!<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>WebPageTest<\/strong><\/h3>\n<p><a href=\"https:\/\/www.webpagetest.org\/\" target=\"_blank\" rel=\"noopener\">WebPageTest<\/a> erm\u00f6glicht Tests aus mehreren Standorten. Es bietet einen visuellen Vergleich, detaillierte Leistungsinformationen und eine Aufschl\u00fcsselung der Core Web Vitals.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Lighthouse<\/strong><\/h3>\n<p><a href=\"https:\/\/chromewebstore.google.com\/detail\/lighthouse\/blipmdconlkpinefehnmjammfjpmpbjk?hl=es\" target=\"_blank\" rel=\"noopener\">Lighthouse <\/a>ist ein Tool, das in die Chrome DevTools integriert ist. Es bietet verschiedene Audits f\u00fcr die Leistung, wie Zug\u00e4nglichkeit, Progressive Web Apps, SEO und mehr.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Wie verbessert man die Core Web Vitals?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h3><strong>1. Reserve space for ad units<\/strong><\/h3>\n<p>Vermeide Layoutverschiebungen, indem du den Platz f\u00fcr die H\u00f6he der Anzeige reservierst.\u00a0<a href=\"https:\/\/refinery89.com\/de\/4-strategien-zur-anzeigenplatzierung-zur-maximierung-der-einnahmen\/\" target=\"_blank\" rel=\"noopener\">Erfahre mehr \u00fcber diese und andere Strategien zur Optimierung der Anzeigepositionierung und zur Vermeidung einer schlechten Benutzererfahrung in diesem Artikel von unserem AdOps-Experten Germ\u00e1n Tinaut.<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>2. Improve server response<\/strong><\/h3>\n<p>Verbessere die Backend-Geschwindigkeit, damit der Inhalt, den der Benutzer sehen oder auf den er zugreifen m\u00f6chte, schnell nach der ersten Anfrage angezeigt wird.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>3. Optimize and compress your website\u2019s images<\/strong><\/h3>\n<p>Stelle sicher, dass du moderne Bildformate verwendest, Elemente in der Gr\u00f6\u00dfe anpasst und responsives Webdesign implementierst, um eine schnelle Ladezeit zu gew\u00e4hrleisten.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>4. Optimize the JavaScript<\/strong><\/h3>\n<p>Minimiere und verz\u00f6gere das Laden von nicht-kritischem JavaScript, um den Haupt-Thread nicht zu blockieren. Erw\u00e4ge Code-Splitting-Techniken oder teile Skripte in kleinere Teile auf.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>5. Leverage Lazy Loading<\/strong><\/h3>\n<p>Verz\u00f6gere das Laden von Bildern au\u00dferhalb des Bildschirms, um den anfangs sichtbaren Inhalt durch die Implementierung von\u00a0<a href=\"https:\/\/refinery89.com\/de\/lazy-loading-in-programmatic-advertising\/\" target=\"_blank\" rel=\"noopener\">Lazy Loading<\/a>. Lazy Loading ist eine Technik, die das Laden von nicht-kritischen Ressourcen zum Ladezeitpunkt der Seite verz\u00f6gert. Anstatt alle Assets gleichzeitig zu laden, wartet es, bis der sichtbare Bereich des Browsers des Benutzers kurz davor ist, ein Element anzuzeigen, bevor es geladen wird.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>6. Reduce Third-Party script Impact<\/strong><\/h3>\n<p>\u00dcberpr\u00fcfe Drittanbieter-Skripte (wie Analyse- oder Marketing-Tags) und optimiere deren Ladezeiten, um die Beeintr\u00e4chtigung zu verringern.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>7. Utilize a Content Delivery Network (CDN)<\/strong><\/h3>\n<p>Verteile deine Web-Ressourcen \u00fcber ein\u00a0<a href=\"https:\/\/aws.amazon.com\/what-is\/cdn\/\" target=\"_blank\" rel=\"noopener\">Content Delivery Network (CDN).<\/a>\u00a0Dies ist ein Netzwerk geografisch verteilter Server, das hilft, die Ladegeschwindigkeit der Webseiten zu erh\u00f6hen. Diese Server speichern zwischengespeicherte Kopien des Inhalts deiner Website und liefern sie vom n\u00e4chstgelegenen Standort des Benutzers. Dies hilft, Ladezeiten basierend auf den geografischen Standorten der Benutzer zu reduzieren und die Leistung deiner Website zu verbessern.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>8. Optimize your fonts<\/strong><\/h3>\n<p>Setze die Werte von font-display um, lade Web-Schriftarten vor oder verwende Schriftgr\u00f6\u00dfen, die mit den System-Fallback-Schriften \u00fcbereinstimmen, um Textdarstellungs\u00e4nderungen zu verringern.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>9. Specify size dimensions for images and videos<\/strong><\/h3>\n<p>Die Verwendung der Attribute f\u00fcr Breite und H\u00f6he bei Medientags verhindert Reflows, da der Browser w\u00e4hrend des Ladevorgangs Platz daf\u00fcr reserviert.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Monetisiere deine Website, ohne deine Core Web Vitals zu opfern!<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Die richtige L\u00f6sung f\u00fcr die Anzeigenmonetarisierung, die deine Werbeeinnahmen maximiert und gleichzeitig deine Core Web Vitals sch\u00fctzt, ist wie ein Jackpot! Unsere preisgekr\u00f6nte Single-Tag-Anzeigenmonetarisierungsl\u00f6sung ist nicht nur mit den besten Funktionen ausgestattet, um deine Anzeigensstrategie zu verbessern, sondern auch speziell darauf ausgelegt, die Leistung deiner Website nicht zu st\u00f6ren. Zus\u00e4tzlich wirst du von einem Expertenteam unterst\u00fctzt, das dir bei der Optimierung der Anzeigenschaltung hilft, was zu besseren Core Web Vitals f\u00fchrt. <a href=\"https:\/\/refinery89.com\/de\/kontaktieren-sie-uns-refinery89\/\" target=\"_blank\" rel=\"noopener\">Kontaktiere uns, um mehr zu erfahren!<\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Continuously optimizing your website is just what the doctor ordered to maintain a healthy ad strategy and one way to do it is by keeping in check your Core Web Vitals. These famous metrics will describe your website\u2019s performance, providing you with insights of improvements to elevate your user experience, search engine positioning, and most [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":13366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131,22,14,20],"tags":[82,24,72,34,65],"class_list":["post-13363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company-news","category-news","category-partner_solutions","category-refinery-academy","tag-core-web-vitals","tag-programmatic-advertising","tag-publishers","tag-refinery-academy","tag-seo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Core Web Vitals: The Ultimate Guide - Refinery89<\/title>\n<meta name=\"description\" content=\"Learn all about Google&#039;s Core Web Vitals in this comprehensive guide. Discover what are they, how to track them, and how to improve them!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/refinery89.com\/de\/core-web-vitals-der-guide\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Core Web Vitals: The Ultimate Guide - Refinery89\" \/>\n<meta property=\"og:description\" content=\"Learn all about Google&#039;s Core Web Vitals in this comprehensive guide. Discover what are they, how to track them, and how to improve them!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/refinery89.com\/de\/core-web-vitals-der-guide\/\" \/>\n<meta property=\"og:site_name\" content=\"Refinery89\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Refinery89\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T11:28:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-16T13:14:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patricia Sim\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@refinery89\" \/>\n<meta name=\"twitter:site\" content=\"@refinery89\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Sim\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/\"},\"author\":{\"name\":\"Patricia Sim\u00f3n\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/#\\\/schema\\\/person\\\/73d11fd427b79cf70aa553e3b9d33f7d\"},\"headline\":\"Core Web Vitals: The ultimate guide to enhance site&#8217;s performance\",\"datePublished\":\"2025-03-20T11:28:10+00:00\",\"dateModified\":\"2025-07-16T13:14:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/\"},\"wordCount\":1548,\"publisher\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Blog-Post_CWV-Complete-Guide.png\",\"keywords\":[\"Core Web Vitals\",\"Programmatic Advertising\",\"Publishers\",\"Refinery Academy\",\"SEO\"],\"articleSection\":[\"Company News\",\"News\",\"Partner solutions\",\"Refinery Academy\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/\",\"url\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/\",\"name\":\"Core Web Vitals: The Ultimate Guide - Refinery89\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Blog-Post_CWV-Complete-Guide.png\",\"datePublished\":\"2025-03-20T11:28:10+00:00\",\"dateModified\":\"2025-07-16T13:14:05+00:00\",\"description\":\"Learn all about Google's Core Web Vitals in this comprehensive guide. Discover what are they, how to track them, and how to improve them!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#primaryimage\",\"url\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Blog-Post_CWV-Complete-Guide.png\",\"contentUrl\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Blog-Post_CWV-Complete-Guide.png\",\"width\":800,\"height\":550,\"caption\":\"Core Web Vitals guide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/core-web-vitals-guide\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/refinery89.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Core Web Vitals: The ultimate guide to enhance site&#8217;s performance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/#website\",\"url\":\"https:\\\/\\\/refinery89.com\\\/\",\"name\":\"Refinery89\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/refinery89.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/#organization\",\"name\":\"Refinery89\",\"alternateName\":\"R89\",\"url\":\"https:\\\/\\\/refinery89.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/r89-thumbnail.png\",\"contentUrl\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/r89-thumbnail.png\",\"width\":200,\"height\":200,\"caption\":\"Refinery89\"},\"image\":{\"@id\":\"https:\\\/\\\/refinery89.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Refinery89\\\/\",\"https:\\\/\\\/x.com\\\/refinery89\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/refinery89\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@refinery89\",\"https:\\\/\\\/www.instagram.com\\\/refinery_89\\\/\",\"https:\\\/\\\/www.reddit.com\\\/user\\\/Refinery89\\\/\",\"https:\\\/\\\/share.google\\\/K8hFf3ktmUrTi1XCa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/#\\\/schema\\\/person\\\/73d11fd427b79cf70aa553e3b9d33f7d\",\"name\":\"Patricia Sim\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/patricia-simon_avatar-96x96.png\",\"url\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/patricia-simon_avatar-96x96.png\",\"contentUrl\":\"https:\\\/\\\/refinery89.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/patricia-simon_avatar-96x96.png\",\"caption\":\"Patricia Sim\u00f3n\"},\"description\":\"Patricia Sim\u00f3n is Refinery89\u2019s Inbound and Content Specialist. With expertise in digital marketing, SEO, and ad tech trends, Patricia creates content that translates complex programmatic advertising topics into actionable insights, empowering publishers and advertisers to thrive.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/patriciasimonmarketing\\\/\"],\"url\":\"https:\\\/\\\/refinery89.com\\\/de\\\/author\\\/patri\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Core Web Vitals: Der ultimative Guide - Refinery89","description":"Lerne alles \u00fcber die Core Web Vitals von Google in diesem umfassenden Leitfaden. Erfahre, was sie sind, wie man sie misst und wie man sie verbessern kann!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/refinery89.com\/de\/core-web-vitals-der-guide\/","og_locale":"de_DE","og_type":"article","og_title":"Core Web Vitals: The Ultimate Guide - Refinery89","og_description":"Learn all about Google's Core Web Vitals in this comprehensive guide. Discover what are they, how to track them, and how to improve them!","og_url":"https:\/\/refinery89.com\/de\/core-web-vitals-der-guide\/","og_site_name":"Refinery89","article_publisher":"https:\/\/www.facebook.com\/Refinery89\/","article_published_time":"2025-03-20T11:28:10+00:00","article_modified_time":"2025-07-16T13:14:05+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png","type":"image\/png"}],"author":"Patricia Sim\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@refinery89","twitter_site":"@refinery89","twitter_misc":{"Verfasst von":"Patricia Sim\u00f3n","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#article","isPartOf":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/"},"author":{"name":"Patricia Sim\u00f3n","@id":"https:\/\/refinery89.com\/#\/schema\/person\/73d11fd427b79cf70aa553e3b9d33f7d"},"headline":"Core Web Vitals: The ultimate guide to enhance site&#8217;s performance","datePublished":"2025-03-20T11:28:10+00:00","dateModified":"2025-07-16T13:14:05+00:00","mainEntityOfPage":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/"},"wordCount":1548,"publisher":{"@id":"https:\/\/refinery89.com\/#organization"},"image":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png","keywords":["Core Web Vitals","Programmatic Advertising","Publishers","Refinery Academy","SEO"],"articleSection":["Company News","News","Partner solutions","Refinery Academy"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/","url":"https:\/\/refinery89.com\/core-web-vitals-guide\/","name":"Core Web Vitals: Der ultimative Guide - Refinery89","isPartOf":{"@id":"https:\/\/refinery89.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#primaryimage"},"image":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#primaryimage"},"thumbnailUrl":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png","datePublished":"2025-03-20T11:28:10+00:00","dateModified":"2025-07-16T13:14:05+00:00","description":"Lerne alles \u00fcber die Core Web Vitals von Google in diesem umfassenden Leitfaden. Erfahre, was sie sind, wie man sie misst und wie man sie verbessern kann!","breadcrumb":{"@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/refinery89.com\/core-web-vitals-guide\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#primaryimage","url":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png","contentUrl":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/03\/Blog-Post_CWV-Complete-Guide.png","width":800,"height":550,"caption":"Core Web Vitals guide"},{"@type":"BreadcrumbList","@id":"https:\/\/refinery89.com\/core-web-vitals-guide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/refinery89.com\/"},{"@type":"ListItem","position":2,"name":"Core Web Vitals: The ultimate guide to enhance site&#8217;s performance"}]},{"@type":"WebSite","@id":"https:\/\/refinery89.com\/#website","url":"https:\/\/refinery89.com\/","name":"Refinery89","description":"","publisher":{"@id":"https:\/\/refinery89.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/refinery89.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/refinery89.com\/#organization","name":"Refinery89","alternateName":"R89","url":"https:\/\/refinery89.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/refinery89.com\/#\/schema\/logo\/image\/","url":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/08\/r89-thumbnail.png","contentUrl":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/08\/r89-thumbnail.png","width":200,"height":200,"caption":"Refinery89"},"image":{"@id":"https:\/\/refinery89.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Refinery89\/","https:\/\/x.com\/refinery89","https:\/\/www.linkedin.com\/company\/refinery89\/","https:\/\/www.youtube.com\/@refinery89","https:\/\/www.instagram.com\/refinery_89\/","https:\/\/www.reddit.com\/user\/Refinery89\/","https:\/\/share.google\/K8hFf3ktmUrTi1XCa"]},{"@type":"Person","@id":"https:\/\/refinery89.com\/#\/schema\/person\/73d11fd427b79cf70aa553e3b9d33f7d","name":"Patricia Sim\u00f3n","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/02\/patricia-simon_avatar-96x96.png","url":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/02\/patricia-simon_avatar-96x96.png","contentUrl":"https:\/\/refinery89.com\/wp-content\/uploads\/2025\/02\/patricia-simon_avatar-96x96.png","caption":"Patricia Sim\u00f3n"},"description":"Patricia Sim\u00f3n ist Inbound und Content Specialist bei Refinery89. Mit Expertise in den Bereichen Digital Marketing, SEO und Ad-Tech-Trends erstellt Patricia Inhalte, die komplexe programmatische Werbethemen in umsetzbare Erkenntnisse \u00fcbersetzen und Publishern sowie Werbetreibenden dabei helfen, erfolgreich zu sein.","sameAs":["https:\/\/www.linkedin.com\/in\/patriciasimonmarketing\/"],"url":"https:\/\/refinery89.com\/de\/author\/patri\/"}]}},"_links":{"self":[{"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/posts\/13363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/comments?post=13363"}],"version-history":[{"count":0,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/posts\/13363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/media\/13366"}],"wp:attachment":[{"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/media?parent=13363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/categories?post=13363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/refinery89.com\/de\/wp-json\/wp\/v2\/tags?post=13363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}